{"id":17,"count":3,"description":"","link":"https:\/\/www.connect-d.com\/blog\/archives\/category\/read\/scandinavian-trip","name":"\u5317\u6b27\u51fa\u5f35\u8a18","slug":"scandinavian-trip","taxonomy":"category","parent":4,"meta":[],"_links":{"self":[{"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/posts?categories=17"},{"href":"https:\/\/www.connect-d.com\/blog\/wp-json\/wp\/v2\/pages?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}